{"id":152,"count":0,"description":"4x4 tires built for enhanced traction and control, ideal for off-road adventures and rugged driving conditions.","link":"https:\/\/superfix.ae\/ur\/product-category\/car-tires\/4x4-tires\/","name":"4x4 Tires","slug":"4x4-tires","taxonomy":"product_cat","parent":149,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.0 (Yoast SEO v25.0) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>4x4 Tires Archives - superfix.ae<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/superfix.ae\/ur\/product-category\/car-tires\/4x4-tires\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"4x4 Tires Archives\" \/>\n<meta property=\"og:description\" content=\"4&#215;4 tires built for enhanced traction and control, ideal for off-road adventures and rugged driving conditions.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/superfix.ae\/ur\/product-category\/car-tires\/4x4-tires\/\" \/>\n<meta property=\"og:site_name\" content=\"superfix.ae\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/superfix.ae\/product-category\/car-tires\/4x4-tires\/\",\"url\":\"https:\/\/superfix.ae\/product-category\/car-tires\/4x4-tires\/\",\"name\":\"4x4 Tires Archives - superfix.ae\",\"isPartOf\":{\"@id\":\"https:\/\/superfix.ae\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/superfix.ae\/product-category\/car-tires\/4x4-tires\/#breadcrumb\"},\"inLanguage\":\"ur\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/superfix.ae\/product-category\/car-tires\/4x4-tires\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/superfix.ae\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tires\",\"item\":\"https:\/\/superfix.ae\/product-category\/car-tires\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"4x4 Tires\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/superfix.ae\/#website\",\"url\":\"https:\/\/superfix.ae\/\",\"name\":\"superfix.ae\",\"description\":\"superfixautocenters\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/superfix.ae\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ur\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"4x4 Tires Archives - superfix.ae","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/superfix.ae\/ur\/product-category\/car-tires\/4x4-tires\/","og_locale":"en_US","og_type":"article","og_title":"4x4 Tires Archives","og_description":"4&#215;4 tires built for enhanced traction and control, ideal for off-road adventures and rugged driving conditions.","og_url":"https:\/\/superfix.ae\/ur\/product-category\/car-tires\/4x4-tires\/","og_site_name":"superfix.ae","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/superfix.ae\/product-category\/car-tires\/4x4-tires\/","url":"https:\/\/superfix.ae\/product-category\/car-tires\/4x4-tires\/","name":"4x4 Tires Archives - superfix.ae","isPartOf":{"@id":"https:\/\/superfix.ae\/#website"},"breadcrumb":{"@id":"https:\/\/superfix.ae\/product-category\/car-tires\/4x4-tires\/#breadcrumb"},"inLanguage":"ur"},{"@type":"BreadcrumbList","@id":"https:\/\/superfix.ae\/product-category\/car-tires\/4x4-tires\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/superfix.ae\/"},{"@type":"ListItem","position":2,"name":"Tires","item":"https:\/\/superfix.ae\/product-category\/car-tires\/"},{"@type":"ListItem","position":3,"name":"4x4 Tires"}]},{"@type":"WebSite","@id":"https:\/\/superfix.ae\/#website","url":"https:\/\/superfix.ae\/","name":"superfix.ae","description":"superfixautocenters","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/superfix.ae\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ur"}]}},"_links":{"self":[{"href":"https:\/\/superfix.ae\/ur\/wp-json\/wp\/v2\/product_cat\/152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/superfix.ae\/ur\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/superfix.ae\/ur\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/superfix.ae\/ur\/wp-json\/wp\/v2\/product_cat\/149"}],"wp:post_type":[{"href":"https:\/\/superfix.ae\/ur\/wp-json\/wp\/v2\/product?product_cat=152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}